{"id":52348,"date":"2023-04-29T14:15:41","date_gmt":"2023-04-29T18:15:41","guid":{"rendered":"https:\/\/www.fluentu.com\/blog\/?p=52348"},"modified":"2025-06-02T05:52:46","modified_gmt":"2025-06-02T09:52:46","slug":"ingles-conversacional","status":"publish","type":"post","link":"https:\/\/www.fluentu.com\/blog\/english-esp\/ingles-conversacional\/","title":{"rendered":"Mejora tu ingl\u00e9s conversacional: 11 m\u00e9todos que te ayudar\u00e1n a hablar con soltura y seguridad"},"content":{"rendered":"<p>Sabes un mont\u00f3n de <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/vocabulario-de-playa\/\" target=\"_blank\" rel=\"noopener\">vocabulario,<\/a> sabes formar frases, te conoces todas las <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/conversaciones-en-ingles-para-aprender\/\" target=\"_blank\" rel=\"noopener\">estrategias de aprendizaje<\/a>&#8230;<\/p>\n<p>Pero no te salen las palabras cuando quieres mantener una conversaci\u00f3n.<\/p>\n<p>\u00bfPor qu\u00e9 nos cuesta tanto <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/como-hablar-bien-en-ingles\/\" target=\"_blank\" rel=\"noopener\">dominar <\/a>esta habilidad?<\/p>\n<p>En este post te cuento en qu\u00e9 consiste el ingl\u00e9s conversacional, qu\u00e9 necesitas para empaparte del idioma y los m\u00e9todos que tenemos a nuestro alcance para que practiques y ganes soltura.<\/p>\n<p>[fluentu-toc]<\/p>\n<h2><strong>\u00bfQu\u00e9 es el ingl\u00e9s conversacional?<\/strong><\/h2>\n<p>El ingl\u00e9s conversacional es el ingl\u00e9s de todos los d\u00edas, el que se utiliza con amigos, con la familia, en el trabajo&#8230; En definitiva, en cualquier contexto social.<\/p>\n<p>Lo que le diferencia de, por ejemplo, el ingl\u00e9s profesional o t\u00e9cnico, es que en el conversacional empleamos <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/jerga-en-ingles-2\/\" target=\"_blank\" rel=\"noopener\">jerga<\/a>, incluimos <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/modismos-en-ingles-5\/\" target=\"_blank\" rel=\"noopener\">expresiones<\/a>, \u00a1y hasta cometemos <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/errores-gramaticales-en-ingles\/\" target=\"_blank\" rel=\"noopener\">errores gramaticales<\/a>!<\/p>\n<p>Y es que cuando tenemos una conversaci\u00f3n, tendemos a relajarnos; a sentirnos c\u00f3modos hablando.<\/p>\n<p>Dicho esto, es totalmente normal que te trabes al hablar o que, al formular la frase, suene como un trabalenguas. \u00a1Al final este tipo de ingl\u00e9s requiere de mucho o\u00eddo y mucha pr\u00e1ctica!<\/p>\n<p>Y eso se complica un poco cuando no vives en un pa\u00eds angloparlante. \u00a1Pero todo en esta vida tiene soluci\u00f3n! \u00a1Ve\u00e1moslo!<\/p>\n<h2><strong>\u00bfQu\u00e9 necesitas para conseguir un buen nivel de ingl\u00e9s conversacional?<\/strong><\/h2>\n<ul>\n<li><strong>Escucha mucho ingl\u00e9s. <\/strong>Ponte la radio en ingl\u00e9s, escucha <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/podcast-en-ingles-2\/\" target=\"_blank\" rel=\"noopener\">podcasts<\/a>, ve pel\u00edculas y series en ingl\u00e9s con subt\u00edtulos en ingl\u00e9s. Cuanto m\u00e1s inmerso est\u00e9s en el idioma, m\u00e1s lo ir\u00e1s interiorizando sin darte cuenta.<\/li>\n<li><strong>Ampl\u00eda tu vocabulario. <\/strong>Ten siempre a mano una libreta o la aplicaci\u00f3n de notas del m\u00f3vil y apunta cualquier palabra o frase que escuches o leas. \u00a1Nunca sabes cu\u00e1ndo te puede venir bien usarla!<\/li>\n<li><strong>Piensa en ingl\u00e9s.<\/strong> En cualquier situaci\u00f3n o momento, intenta pensar en ingl\u00e9s. \u00bfEst\u00e1s fregando los platos? Piensa c\u00f3mo se dice en ingl\u00e9s cada uno de los cacharros. \u00bfVas a la compra? Busca el t\u00e9rmino adecuado para cada producto.\n<p>Sin darte cuenta, cada vez te costar\u00e1 menos encontrar la traducci\u00f3n correspondiente.<\/li>\n<li><strong>No tengas miedo a fallar. <\/strong>S\u00e9 que una de las cosas que m\u00e1s miedo da a la hora de hablar ingl\u00e9s en p\u00fablico es decir algo mal o no encontrar la palabra adecuada. \u00a1Pero no pasa nada!\n<p>Cualquier persona que est\u00e9 aprendiendo cualquier idioma, va a cometer errores. \u00a1Y da igual si tiene un <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/ingles-avanzado\/\" target=\"_blank\" rel=\"noopener\">nivel avanzado<\/a>!<\/p>\n<p>Es pr\u00e1cticamente imposible decirlo todo perfecto, sin cometer errores de concordancia o equivocarse al decir una palabra. Es totalmente normal y, recuerda que, de los errores se aprende.<\/li>\n<\/ul>\n<h2><strong>11 m\u00e9todos para practicar tu ingl\u00e9s conversacional<\/strong><\/h2>\n<h3>1. Aprovecha la funci\u00f3n de B\u00fasqueda por voz de Google<\/h3>\n<p>Si tienes un dispositivo con micr\u00f3fono, como un tel\u00e9fono u ordenador, lo podr\u00e1s hacer sin problemas. Comprueba que Google entienda lo que dices y convertir\u00e1 tus palabras en texto.<\/p>\n<h3>2. Habla con Alexa o Google Home en ingl\u00e9s<\/h3>\n<p>Si tienes alguno de estos dispositivos, cambia el idioma a ingl\u00e9s y \u00a1tendr\u00e1s un compa\u00f1ero con el que hablar en este idioma!<\/p>\n<p>Pregunta cualquier cosa: qu\u00e9 tiempo va a hacer ma\u00f1ana, cu\u00e1les son las noticias m\u00e1s destacadas o qu\u00e9 ver en <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/peliculas-para-aprender-ingles\/\" target=\"_blank\" rel=\"noopener\">Netflix<\/a>.<\/p>\n<h3>3. \u00a1Haz TikToks!<\/h3>\n<p>Seguro que has visto muchos v\u00eddeos de personas que cuentan lo que han hecho en el d\u00eda, se desahogan contando un problema o hacen videotutoriales de cualquier cosa. \u00bfPor qu\u00e9 no lo haces t\u00fa tambi\u00e9n?<\/p>\n<p>\u00a1Empieza contando por qu\u00e9 te has creado la cuenta! Habla en ingl\u00e9s, sin miedo a cometer errores, y te ayudar\u00e1 a soltarte en la vida real.\u00a0<\/p>\n<p>Cuando no recuerdes una palabra, no te pares, busca otro t\u00e9rmino o reestructura la frase. Esto te ayudar\u00e1 a ser m\u00e1s creativo. Tambi\u00e9n puedes anotar las palabras y frases que olvidaste y luego buscarlas en un diccionario.<\/p>\n<p>\u00a1Y si te da verg\u00fcenza publicarlos, no lo hagas! Puedes dejarlos en borradores e ir comprobando tu avance de vez en cuando.<\/p>\n<p>Tambi\u00e9n puedes usar Instagram con el mismo fin. Sube historias, crea reels o publicaciones en ingl\u00e9s. \u00a1De una forma u otra, sin darte cuenta, ir\u00e1s mejorando tu ingl\u00e9s!<\/p>\n<h3>4. \u00abHabla\u00bb un diario en <a href=\"https:\/\/www.whatsapp.com\/\" target=\"_blank\" rel=\"noopener\">WhatsApp<\/a><\/h3>\n<p>En vez de escribir un diario, h\u00e1blalo. \u00bfEres de esas personas que tiene un chat consigo misma para apuntar la lista de la compra o para que no se le olvide algo?<\/p>\n<p>\u00bfPor qu\u00e9 no utilizarlo como diario? M\u00e1ndate un audio cada d\u00eda. Cuenta en ingl\u00e9s c\u00f3mo te ha ido el d\u00eda, qu\u00e9 has hecho, a qui\u00e9n has visto o d\u00f3nde has estado.<\/p>\n<p>Tambi\u00e9n puedes hacerlo con alg\u00fan amigo. \u00a1Acostumbraos a enviaros audios en ingl\u00e9s!<\/p>\n<p>Cuanto m\u00e1s hables (ya sea contigo mismo o con alguien), m\u00e1s soltura ganar\u00e1s.<\/p>\n<h3><strong>5. Practica el <em>shadowing<\/em><\/strong><\/h3>\n<p>El <em>shadowing<\/em> consiste en imitar. Ponte tu serie o pel\u00edcula favorita, escoge un personaje y pausa cada vez que diga una frase para t\u00fa repetirla.<\/p>\n<p>Copia la entonaci\u00f3n y repite varias veces para asimilarla y, cuando lo tengas que decir en la vida real, te saldr\u00e1 solo.<\/p>\n<div id=\"fluen-2381202658\" style=\"float: right;\"><a data-no-instant=\"1\" href=\"https:\/\/www.fluentu.com\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"FluentU New iOS App Icon\"><img decoding=\"async\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/2021\/12\/iTunesArtwork@1x.png\" alt=\"FluentU New iOS App Icon\"  srcset=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/2021\/12\/iTunesArtwork@1x.png 512w, https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/2021\/12\/iTunesArtwork@1x-300x300.png 300w, https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/2021\/12\/iTunesArtwork@1x-150x150.png 150w, https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/2021\/12\/iTunesArtwork@1x-65x65.png 65w\" sizes=\"(max-width: 512px) 100vw, 512px\" width=\"150\" height=\"150\"   \/><\/a><\/div>\n<p>En <a href=\"https:\/\/www.fluentu.com\/es\/\" target=\"_blank\" rel=\"noopener\">FluentU <\/a>tienes v\u00eddeos de la vida real, como entrevistas, noticias o di\u00e1logos con los que practicar esta t\u00e9cnica. Los v\u00eddeos incluyen sub\u00edtulos, por lo que, si no conoces una palabra o expresi\u00f3n, no tardar\u00e1s en saberla.<\/p>\n<p>Desc\u00e1rgate su app para <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.fluentflix.fluentu&amp;hl=es_419&amp;gl=US\" target=\"_blank\" rel=\"noopener\">Android <\/a>o <a href=\"https:\/\/apps.apple.com\/es\/app\/fluentu-aprende-idiomas\/id917892175\" target=\"_blank\" rel=\"noopener\">iOS<\/a> y practica desde cualquier lugar.<\/p>\n<h3>6. Haz intercambios de idiomas en sitios como <a href=\"http:\/\/www.mylanguageexchange.com\/Search.asp\" target=\"_blank\" rel=\"noopener\">My Language Exchange<\/a><\/h3>\n<p><a href=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/ingles-conversacional-2.png\"><img decoding=\"async\" class=\"alignright wp-image-28408\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/ingles-conversacional-2.png\" alt=\"ingl\u00e9s conversacional\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Existen muchas plataformas en las que puedes encontrar alg\u00fan compa\u00f1ero con el que hablar ingl\u00e9s. Podr\u00e9is hacer viodellamadas, conoceros y practicar el idioma de una forma natural.<\/p>\n<p>Ten en cuenta que muchas de estas personas tampoco son angloparlantes, por lo que, al igual que t\u00fa, buscan lo mismo: poder practicar y hablar en otro idioma que no es el suyo.<\/p>\n<h3>7. Re\u00fanete en Skype con amigos y familiares que hablen ingl\u00e9s<\/h3>\n<p>\u00bfTu prima vive en el extranjero y tiene buen nivel de ingl\u00e9s? Queda con ella por Skype y contaos la vida en ingl\u00e9s.<\/p>\n<p>A veces nos centramos en buscar a un nativo ingl\u00e9s para practicar el <em>speaking<\/em>, \u00a1pero no hace falta! Para ganar soltura y confianza, empieza haci\u00e9ndolo con alguien que conozcas y conf\u00edes.<\/p>\n<h3><strong>8. Traduce todo el rato<\/strong><\/h3>\n<p>Este ejercicio lo puedes integrar en distintas facetas de tu vida. Por dar un ejemplo: imagina que est\u00e1s conduciendo y ves un <a href=\"https:\/\/www.eldebate.com\/motor\/20230403\/insolito-dgt-tutea-conductores-paneles-informativos_105284.html\" target=\"_blank\" rel=\"noopener\">aviso en la carretera<\/a> con una frase.<\/p>\n<p>Intenta traducirla al ingl\u00e9s y decirla en voz alta con buena pronunciaci\u00f3n.<\/p>\n<h3><strong>9. Desc\u00e1rgate <\/strong><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.wordreference&amp;hl=en\" target=\"_blank\" rel=\"noopener\"><strong>WordReference<\/strong><\/a><\/h3>\n<p><a href=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/5\/WordReference-Dictionary-1.png\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"size-thumbnail wp-image-87080 alignright\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/5\/WordReference-Dictionary-1-150x150.png\" alt=\"\" srcset=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/5\/WordReference-Dictionary-1-150x150.png 150w, https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/5\/WordReference-Dictionary-1-65x65.png 65w, https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/5\/WordReference-Dictionary-1-120x120.png 120w, https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/5\/WordReference-Dictionary-1.png 288w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>WordReference destaca por contar con <strong>dos funciones que te permiten practicar tu ingl\u00e9s conversacional<\/strong>.<\/p>\n<p>En primer lugar, la aplicaci\u00f3n dice en voz alta las palabras; algo estupendo para entender mejor la pronunciaci\u00f3n.<\/p>\n<p>Para aprovechar al m\u00e1ximo esta funci\u00f3n, repite la palabra en voz alta e imita la pronunciaci\u00f3n de la aplicaci\u00f3n. Puedes elegir entre voz brit\u00e1nica o estadounidense.<\/p>\n<p>La segunda funci\u00f3n es la b\u00fasqueda en contexto. Siempre que busques el significado de una palabra, podr\u00e1s ver una definici\u00f3n y frases de ejemplo.<\/p>\n<p>Y no son frases b\u00e1sicas, sino ejemplos del mundo real que muestran c\u00f3mo se usa la palabra en situaciones reales.<\/p>\n<p>Adem\u00e1s, <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/foros-para-aprender-ingles\/\" target=\"_blank\" rel=\"noopener\">hay foros<\/a> donde los estudiantes pueden hacer preguntas y recibir respuestas. Visita estos foros y mira c\u00f3mo los hablantes nativos explican c\u00f3mo usan ellos ciertas palabras o expresiones.<\/p>\n<h3><strong>10. Visita la <\/strong><a href=\"https:\/\/www.verbling.com\/es\/discussions\/en\" target=\"_blank\" rel=\"noopener\"><strong>comunidad de Verbling<\/strong><\/a><\/h3>\n<p><a href=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/ingles-conversacional.png\"><img decoding=\"async\" class=\"alignright wp-image-28406\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/ingles-conversacional.png\" alt=\"ingl\u00e9s conversacional\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Los debates de la comunidad de Verbling est\u00e1n compuestos de varios grupos de chat en el que se tratan distintos temas.<\/p>\n<p>El creador de la charla (que suele ser un tutor de ingl\u00e9s) publica una pregunta o algo interesante, animando a que los alumnos respondan.<\/p>\n<p>Aprovecha este sitio web para chatear con hablantes nativos y otros estudiantes de ingl\u00e9s de manera gratuita. Los debates est\u00e1n abiertos a todo el p\u00fablico y fluyen naturalmente.<\/p>\n<p>La gente siempre est\u00e1 dispuesta a ayudar con los errores y nadie juzga a quienes los cometen.<\/p>\n<p>A medida que converses m\u00e1s y m\u00e1s (sin sentir miedo de tus errores), ver\u00e1s c\u00f3mo va mejorando tu ingl\u00e9s conversacional.<\/p>\n<h3><strong>11. Visita <a href=\"https:\/\/www.hellotalk.com\/\" target=\"_blank\" rel=\"noopener\">HelloTalk<\/a><\/strong><\/h3>\n<p><a href=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/ingles-conversacional-1.png\"><img decoding=\"async\" class=\"alignright wp-image-28407\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/ingles-conversacional-1.png\" alt=\"ingl\u00e9s conversacional\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>HelloTalk es una aplicaci\u00f3n de texto con la que puedes practicar tu ingl\u00e9s conversacional con hablantes de diferentes idiomas.<\/p>\n<p>En la app puedes elegir cualquier idioma. La mayor\u00eda de personas en la aplicaci\u00f3n buscan practicar su ingl\u00e9s tal como t\u00fa, as\u00ed que encontrar\u00e1s a un compa\u00f1ero r\u00e1pido.<\/p>\n<p>Pero si lo que quieres es mejorar el <em>speaking,<\/em> \u00bfc\u00f3mo podr\u00eda ayudarte una aplicaci\u00f3n de texto?<\/p>\n<p>Bien, HelloTalk cuenta con una funci\u00f3n en su teclado que te permite enviar mensajes de voz. A su vez, tu compa\u00f1ero puede responderte con otro mensaje de voz. Adem\u00e1s, si recibes un texto, la aplicaci\u00f3n puede le\u00e9rtelo en voz alta.<\/p>\n<p>Esta funci\u00f3n resulta muy \u00fatil para mejorar tu pronunciaci\u00f3n, ya que la aplicaci\u00f3n tiene una entonaci\u00f3n muy clara.<\/p>\n<h2><strong>\u00bfPor qu\u00e9 nos cuesta tanto hablar en ingl\u00e9s?<\/strong><\/h2>\n<p>Muchas veces tiene que ver con la seguridad en uno mismo. Si vives en un pa\u00eds donde el ingl\u00e9s no es la lengua predominante, donde no est\u00e1s constantemente expuesto al idioma, sientes que no sabes suficiente como para tener una conversaci\u00f3n.<\/p>\n<p>Tambi\u00e9n es cierto que, en el cole o en las academias, suelen centrarse en la lectura, escritura y escucha y se incide poco en el habla, y por eso acaba siendo la habilidad menos practicada.<\/p>\n<p>Casi todos sentimos ese miedo a la hora de hablar en ingl\u00e9s; ese miedo a que no te entiendan o a decir algo mal.<\/p>\n<p>Piensa que el habla es de las habilidades m\u00e1s dif\u00edciles y que m\u00e1s cuesta dominar en un idioma. No te sientas mal, \u00a1es algo totalmente normal!<\/p>\n<p>Incluso t\u00fa mismo te dar\u00e1s cuenta de que has dicho algo mal o que hubiese sido mejor elegir otra palabra. \u00a1Y sin darte cuenta est\u00e1s mejorando tu ingl\u00e9s porque ya eres consciente de d\u00f3nde fallas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabes un mont\u00f3n de vocabulario, sabes formar frases, te conoces todas las estrategias de aprendizaje&#8230; Pero no te salen las palabras cuando quieres mantener una conversaci\u00f3n. \u00bfPor qu\u00e9 nos cuesta&hellip;<\/p>\n","protected":false},"author":160,"featured_media":252209,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"Mejora tu ingl\u00e9s conversacional: 11 m\u00e9todos que te ayudar\u00e1n a hablar con soltura y seguridad | FluentU Blog de Ingl\u00e9s","description":"Hablar ingl\u00e9s cuesta; nos pasa a todos. En el ingl\u00e9s conversacional hay mucha jerga, coloquialismos y abreviaturas que hacen que sea diferente del ingl\u00e9s acad\u00e9mico o profesional. \u00a1En este post te ense\u00f1o 11 m\u00e9todos y consejos para que practiques el speaking de muchas formas! \u00a1Ganar\u00e1s soltura y seguridad!"},"footnotes":""},"categories":[347,351],"tags":[],"coauthors":[343,370,372],"class_list":["post-52348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-english-esp","category-recursos-para-aprender-ingles"],"_links":{"self":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts\/52348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/comments?post=52348"}],"version-history":[{"count":5,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts\/52348\/revisions"}],"predecessor-version":[{"id":254041,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts\/52348\/revisions\/254041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/media\/252209"}],"wp:attachment":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/media?parent=52348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/categories?post=52348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/tags?post=52348"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/coauthors?post=52348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}