{"id":51813,"date":"2023-11-03T16:07:20","date_gmt":"2023-11-03T20:07:20","guid":{"rendered":"https:\/\/www.fluentu.com\/blog\/?p=51813"},"modified":"2025-01-27T06:17:50","modified_gmt":"2025-01-27T11:17:50","slug":"vocabulario-de-pascua","status":"publish","type":"post","link":"https:\/\/www.fluentu.com\/blog\/english-esp\/vocabulario-de-pascua\/","title":{"rendered":"Vocabulario de Pascua en ingl\u00e9s y frases para felicitar estas fiestas [con audios]"},"content":{"rendered":"<p>Sigue leyendo para aprender las frases y el vocabulario de Pascua en ingl\u00e9s, \u00a1y las costumbres de esta festividad!<\/p>\n<p>Ya sabes que en los pa\u00edses anglosajones se celebra <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/vocabulario-thanksgiving\/\" target=\"_blank\" rel=\"noopener\">Acci\u00f3n de Gracias<\/a>, <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/tradiciones-de-navidad-en-ingles\/\" target=\"_blank\" rel=\"noopener\">Navidad<\/a>, <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/vocabulario-san-valentin\/\" target=\"_blank\" rel=\"noopener\">San Valent\u00edn<\/a>&#8230; \u00a1Y la Pascua no puede faltar!<\/p>\n<p>Aunque las celebraciones de este d\u00eda <a href=\"https:\/\/www.fluentu.com\/blog\/english-esp\/paises-donde-se-habla-ingles\/\" target=\"_blank\" rel=\"noopener\">var\u00edan de un pa\u00eds a otro<\/a>, existen algunas similitudes. \u00a1Vamos a ello!<\/p>\n<p>[fluentu-toc]<\/p>\n<h2>S\u00edmbolos y decoraciones de Pascua<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-46471\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/vocabulario-de-pascua-en-ingles.jpg\" alt=\"Easter bunny and eggs\" \/><\/p>\n<p><strong>1. <em>Easter Bunny<\/em>\u00a0(Conejo de Pascua)<\/p>\n<p><\/strong>Dicen que el Conejo de Pascua esconde huevos de Pascua para que los ni\u00f1os los encuentren. Representa la llegada de la primavera y la alegr\u00eda.<\/p>\n<p><strong>2. <em>Easter eggs<\/em>\u00a0(Huevos de Pascua)<\/p>\n<p><\/strong>Los ni\u00f1os (y tambi\u00e9n adultos) pintan y decoran los huevos durante estos d\u00edas.<\/p>\n<p><strong>3. <em>Easter basket<\/em>\u00a0(Cesta de Pascua)<\/strong><\/p>\n<p>Cuando el Consejo de Pascua deja los huevos, los ni\u00f1os usan esta cesta para recogerlos.<\/p>\n<p><strong>4. <em>Easter egg hunt<\/em>\u00a0(B\u00fasqueda de huevos de Pascua)<\/strong><\/p>\n<p>\u00a1Esto es lo que todos los ni\u00f1os desean hacer cuando se acerca esta fecha! \u00a1A ver qui\u00e9n encuentra m\u00e1s!<\/p>\n<p><strong>5. <em>Chocolate bunny<\/em>\u00a0(Conejo de chocolate)<\/strong><\/p>\n<p>Los conejos de chocolate son un dulce muy popular de Pascua.<\/p>\n<p><strong>6. <em>Chick<\/em>\u00a0(Pollito)<\/strong><\/p>\n<p>Los pollitos tambi\u00e9n est\u00e1n relacionados con la Pascua porque, en tiempos paganos, simbolizaban la fertilidad y la nueva vida.<\/p>\n<p><strong>7. <em>Cross<\/em> (Cruz)<\/strong><\/p>\n<p>La cruz es un s\u00edmbolo religioso en la Pascua, ya que representa la crucifixi\u00f3n y resurrecci\u00f3n de Jes\u00fas. Es un recordatorio del significado religioso de la festividad.<\/p>\n<p><strong>8. <em>Lilies<\/em> (Lirios)<\/strong><\/p>\n<p>Las flores de lirio son comunes en la decoraci\u00f3n de Pascua y simbolizan la pureza y la esperanza. Tambi\u00e9n se asocian con la resurrecci\u00f3n de Cristo.<\/p>\n<p><strong>9. <em>Bonnet<\/em>\u00a0(Sombrero de Pascua)<\/p>\n<p><\/strong>Los <a href=\"https:\/\/www.mentalfloss.com\/posts\/easter-bonnet-history\" target=\"_blank\" rel=\"noopener\">sombreros de Pascua<\/a> se suelen decorar con flores y lazos y simbolizan lo nuevo, la renovaci\u00f3n.<\/p>\n<h2><strong>Comida y dulces de Pascua<\/strong><\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-46472\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/vocabulario-de-pascua-en-ingles-1.jpg\" alt=\"Easter cake\" \/><\/p>\n<p><strong>10. <em>Hot cross buns<\/em><\/strong><\/p>\n<p>Son unos bollos que se elaboran con mantequilla, leche, canela y pasas. Yummy!<\/p>\n<p><strong>11. <em>Peeps<\/em><\/strong><\/p>\n<p>Unos peque\u00f1os malvaviscos con forma de pollito que son un producto t\u00edpico de Pascua muy misterioso. \u00a1Existen muchas teor\u00edas acerca de por qu\u00e9 los Peeps son un s\u00edmbolo de la Pascua!<\/p>\n<p class=\"wp-block-heading\"><strong>12. <em>Easter bread<\/em><\/strong><\/p>\n<p>El pan est\u00e1 muy relacionado con Jes\u00fas. Simboliza el cuerpo de Cristo y siempre ha formado parte de la celebraci\u00f3n de la Pascua. \u00a1Este pan suele ser dulce!<\/p>\n<p><strong>13. <em>Cooked ham<\/em><\/strong><\/p>\n<p>Puede que sea la comida de Pascua m\u00e1s conocida. Se puede hacer al horno con miel, con sirope de arce o <a href=\"https:\/\/www.thespruceeats.com\/glazed-spiral-sliced-ham-recipe-480790\" target=\"_blank\" rel=\"noopener\">cortado en espiral<\/a>. \u00a1En muchas casas se prepara esta deliciosa carne para la cena de Pascua!<\/p>\n<p><strong>14. <em>Roasted lamb<\/em><\/strong><\/p>\n<p>Si no se hace jam\u00f3n, entonces seguramente se haga cordero. \u00a1Otro cl\u00e1sico de esta festividad!<\/p>\n<h2>Actividades del d\u00eda de Pascua<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-46473\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/vocabulario-de-pascua-en-ingles-2.jpg\" alt=\"Kids painting eggs\" \/><\/p>\n<p><strong>15. <em>Attend an Easter parade<\/em> (Ir a un desfile de Pascua)<\/strong><\/p>\n<p><strong>16. <em>Decorate Easter eggs<\/em> (Decorar huevos de Pascua)<\/strong><\/p>\n<p><strong>17. <em>Attend a church service<\/em> (Ir a misa)<\/strong><\/p>\n<p><strong>18. <em>Easter egg roll<\/em> (<a href=\"https:\/\/whitehouse.gov1.info\/easter-egg-roll\/\" target=\"_blank\" rel=\"noopener\">Carrera de rodar huevos de Pascua<\/a>)<\/strong><\/p>\n<p><b>19. <em>Enjoying festive meals with family and friends<\/em> (Disfrutar de comidas especiales con la familia y los amigos)<\/b><\/p>\n<p><strong>20. <em>Easter break<\/em> (Vacaciones de Semana Santa)<\/strong><\/p>\n<h2>Religi\u00f3n<\/h2>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-46474\" src=\"https:\/\/www.fluentu.com\/blog\/wp-content\/uploads\/site\/\/3\/vocabulario-de-pascua-en-ingles-3.jpg\" alt=\"A priest celebrating a holy mass\" \/><\/p>\n<p><strong>21. <em>Palm Sunday<\/em> (Domingo de Ramos)<\/strong><\/p>\n<p><b><strong>22. <em>Ash Wednesday<\/em> (<\/strong><\/b><strong>Mi\u00e9rcoles de Ceniza)<\/strong><\/p>\n<p><strong>23. <em>Lent<\/em> (Cuaresma)<\/strong><\/p>\n<p><b><strong>24. <em>Passion of Christ<\/em> (<\/strong><\/b><strong>Pasi\u00f3n de Cristo)<\/strong><\/p>\n<p><strong>25. <em>Holy Week<\/em> (Semana Santa)<\/strong><\/p>\n<p><strong>26. <em>Maundy Thursday<\/em> (Jueves Santo)<\/strong><\/p>\n<p><strong>27. <em>Good Friday<\/em> (Viernes Santo)<\/strong><\/p>\n<h2>Frases para decir el d\u00eda de Pascua<\/h2>\n<p>\u00a1Apunta estas frases para dedicar a la gente que m\u00e1s quieres!<\/p>\n<p><strong>28. <em>Happy Easter!<\/em><\/strong><\/p>\n<p>\u00a1Felices Pascuas!<\/p>\n<p><strong>29. <em>Easter blessings to you and your family.<\/em><\/strong><\/p>\n<p>Bendiciones de Pascua para ti y tu familia.<\/p>\n<p><strong>30. <em>Have a joyful Easter celebration.<\/em><\/strong><\/p>\n<p>Que tengas unas Pascuas llenas de alegr\u00eda.<\/p>\n<p><strong>31. <em>May your Easter be filled with love and happiness.<\/em><\/strong><\/p>\n<p>Que pases la Pascua rodeado de amor y felicidad.<\/p>\n<p><strong>32. <em>Wishing you a peaceful and blessed Easter.<\/em><\/strong><\/p>\n<p>Te deseo una Pascua llena de paz y bendiciones.<\/p>\n<p><strong>34. <em>Enjoy the Easter egg hunt with your family.<\/em><\/strong><\/p>\n<p>Disfruta la b\u00fasqueda de huevos de Pascua con tu familia.<\/p>\n<p><strong>35. <em>Sending warm Easter wishes your way.<\/em><\/strong><\/p>\n<p>Te env\u00edo los mejores deseos de Pascua.<\/p>\n<p>&nbsp;<\/p>\n<p>Happy Easter!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sigue leyendo para aprender las frases y el vocabulario de Pascua en ingl\u00e9s, \u00a1y las costumbres de esta festividad! Ya sabes que en los pa\u00edses anglosajones se celebra Acci\u00f3n de&hellip;<\/p>\n","protected":false},"author":586,"featured_media":248609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"Vocabulario de Pascua en ingl\u00e9s y frases para felicitar estas fiestas [con audios] | FluentU Blog de ingl\u00e9s","description":"Ya se acerca la Pascua, \u00bfsabes qu\u00e9 tradiciones siguen los pa\u00edses anglosajones? Atento a este post donde aprender\u00e1s el vocabulario de Pascua en ingl\u00e9s clave para a\u00f1adir a tu repertorio ling\u00fc\u00edstico. Adem\u00e1s, tambi\u00e9n tienes unas cuantas frases relacionadas con la Pascua para felicitar las fiestas a quien t\u00fa quieras."},"footnotes":""},"categories":[347,348],"tags":[],"coauthors":[370],"class_list":["post-51813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-english-esp","category-vocabulario-en-ingles"],"_links":{"self":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts\/51813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/users\/586"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/comments?post=51813"}],"version-history":[{"count":1,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts\/51813\/revisions"}],"predecessor-version":[{"id":51903,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/posts\/51813\/revisions\/51903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/media\/248609"}],"wp:attachment":[{"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/media?parent=51813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/categories?post=51813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/tags?post=51813"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.fluentu.com\/blog\/wp-json\/wp\/v2\/coauthors?post=51813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}